{"id":306301,"date":"2022-11-05T17:44:10","date_gmt":"2022-11-05T14:44:10","guid":{"rendered":"https:\/\/ceotudent.com\/la-historia-de-exito-de-walt-disney-despedido-del-periodico-por-decir-poco-creativo"},"modified":"2022-11-05T17:44:10","modified_gmt":"2022-11-05T14:44:10","slug":"la-historia-de-exito-de-walt-disney-despedido-del-periodico-por-decir-poco-creativo","status":"publish","type":"post","link":"https:\/\/ceotudent.com\/es\/la-historia-de-exito-de-walt-disney-despedido-del-periodico-por-decir-poco-creativo","title":{"rendered":"La historia de \u00e9xito de Walt Disney, despedido del peri\u00f3dico por decir poco creativo"},"content":{"rendered":"<p>El pionero de las pel\u00edculas de dibujos animados, el creador de Disneylandia, Walt Disney, conocido como una de las mentes m\u00e1s creativas del siglo XX; Hasta ese momento, fue objeto de innumerables cr\u00edticas como muchas personas exitosas.  Tanto es as\u00ed que fue expulsado del peri\u00f3dico para el que una vez trabaj\u00f3, diciendo que le faltaba creatividad.<\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Cuando Walt era joven, su familia se mudaba constantemente. Tuvo una infancia interrumpida, tratando de adaptarse a otros lugares. Adem\u00e1s, Walt y sus hermanos trabajaban en trabajos peque\u00f1os porque su familia no estaba bien.<\/h2>\n<\/div>\n<div class=\"nImage\" style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/l9d4ma.jpg\"><\/div>\n<div class=\"line nText\">Su familia se mud\u00f3 de Chicago a Missouri y finalmente se estableci\u00f3 en Kansas City cuando Walt ten\u00eda nueve a\u00f1os. Y debido a dificultades financieras, Walt y sus hermanos tuvieron que trabajar. Por estas razones, la vida escolar no pod\u00eda ser la principal prioridad de Walt.<\/div>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"3264820100\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Un adolescente patri\u00f3tico, Walt ten\u00eda 16 a\u00f1os. Se estaba preparando para la Segunda Guerra Mundial, trat\u00f3 de alistarse en el ej\u00e9rcito pero fue rechazado debido a su edad. Pero hab\u00eda encontrado una manera de registrarse.<\/h2>\n<\/div>\n<div class=\"nImage\" style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/ff0m4v.jpg\"><\/div>\n<div class=\"line nText\">Se las arregl\u00f3 para cambiar su fecha de nacimiento en su solicitud para unirse a la unidad de la Cruz Roja. A partir de ese momento, tuvo una personalidad que no tem\u00eda los obst\u00e1culos que se le presentaban y buscaba otras soluciones. Ayud\u00f3 a las operaciones de posguerra durante el resto de la guerra.<\/div>\n<p><amp-ad width=\"100vw\" height=\"320\" type=\"adsense\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"5405056807\" data-auto-format=\"rspv\" data-full-width=\"\"><\/p>\n<div overflow=\"\"><\/div>\n<p><\/amp-ad><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Cuando regres\u00f3, tom\u00f3 un trabajo dibujando caricaturas pol\u00edticas y c\u00f3mics para un peri\u00f3dico. Pero lo despidieron del trabajo, diciendo que no era lo suficientemente creativo. Posteriormente, se embarc\u00f3 en una aventura empresarial a corto plazo.<\/h2>\n<\/div>\n<div class=\"nImage\" style=\"text-align: right;\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/aml77g.jpg\"><\/div>\n<div class=\"line nText\">Su hermano, Roy, trabaj\u00f3 en Rubun Art Studio y jug\u00f3 un papel decisivo en la reuni\u00f3n de Walt Disney con el dibujante Ubbe Iwerks, y se form\u00f3 una compa\u00f1\u00eda de corta duraci\u00f3n \u00abIwerks-Disney Commercial Artists\u00bb.<\/div>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"3264820100\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Walt Disney estaba lleno de emoci\u00f3n y placer por el negocio que fund\u00f3. Estaba fascinado e inmerso en este mundo. Poco despu\u00e9s, encontr\u00f3 una c\u00e1mara prestada en alg\u00fan lugar y cre\u00f3 su propia caricatura llamada \u00abLaugh-O-Grams\u00bb.<\/h2>\n<\/div>\n<div class=\"nImage\" style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/r51ol7.png\"><\/div>\n<p><amp-ad width=\"100vw\" height=\"320\" type=\"adsense\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"5405056807\" data-auto-format=\"rspv\" data-full-width=\"\"><\/p>\n<div overflow=\"\"><\/div>\n<p><\/amp-ad><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Fue un \u00e9xito, de hecho apreciado por Kansas City. Despu\u00e9s de eso, compr\u00f3 un estudio y comenz\u00f3 a crear sus propias animaciones. Aunque pens\u00f3 que le iba muy bien, aun as\u00ed no sucedi\u00f3, quebr\u00f3.<\/h2>\n<\/div>\n<div class=\"nImage\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/0yovmm.jpg\"><\/div>\n<div class=\"line nText\">Aunque fue un paso audaz, quebr\u00f3 porque fue un intento temprano. Disney no ha tenido \u00e9xito en pagar los salarios de sus empleados.<\/div>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"3264820100\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Era alguien que no pod\u00eda rendirse. Vendi\u00f3 su c\u00e1mara y se instal\u00f3 en Hollywood. Empez\u00f3 a aplicar a las ofertas de trabajo de los estudios para la direcci\u00f3n.<\/h2>\n<\/div>\n<div class=\"nImage\" style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/kpknjn.jpg\"><\/div>\n<p><amp-ad width=\"100vw\" height=\"320\" type=\"adsense\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"5405056807\" data-auto-format=\"rspv\" data-full-width=\"\"><\/p>\n<div overflow=\"\"><\/div>\n<p><\/amp-ad><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Como \u00faltimo recurso, le pidi\u00f3 a su hermano Roy y a su amigo, el dibujante Iwerks, que se unieran a \u00e9l, y juntos formaron Disney Brother Studio. \u00a1Las cosas iban bien!<\/h2>\n<\/div>\n<div class=\"nImage\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/hltzmf.jpg\"><\/div>\n<div class=\"line nText\">La serie que iniciaron tuvo \u00e9xito, e incluso uno de los dibujos animados de Walt fue distribuido por la gran empresa Universal.<\/div>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"3264820100\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Iwerks cre\u00f3 un conejo. Aunque Walt no ara\u00f1\u00f3 al conejo, fue Walt quien le dio al conejo la capacidad de moverse, aunque se decidi\u00f3 que Walt ya no era necesario.<\/h2>\n<\/div>\n<div class=\"nImage\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/s0aa8c.jpg\"><\/div>\n<p><amp-ad width=\"100vw\" height=\"320\" type=\"adsense\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"5405056807\" data-auto-format=\"rspv\" data-full-width=\"\"><\/p>\n<div overflow=\"\"><\/div>\n<p><\/amp-ad><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Walt estaba devastado y decidi\u00f3 a partir de ese momento que solo trabajar\u00eda en los personajes que hab\u00eda dibujado, para los cuales ten\u00eda los derechos.<\/h2>\n<\/div>\n<div class=\"nImage\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/im3y4y.jpg\"><\/div>\n<div class=\"line nText\">Mientras abordaba el tren desde Nueva York, Walt sab\u00eda que necesitaba desesperadamente una nueva idea. En el fondo de su mente, siempre tuvo un personaje de rat\u00f3n muy simp\u00e1tico que cre\u00eda que ten\u00eda un gran potencial.<\/div>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"3264820100\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Siempre pensando en un personaje de rat\u00f3n, Walt y \u00e9l hicieron una introducci\u00f3n a la historia mundial de dibujos animados que todos conocemos. Cambi\u00f3 el nombre del rat\u00f3n que llam\u00f3 Mortimer a Mickey Mouse ante la insistencia de su esposa.<\/h2>\n<\/div>\n<div class=\"nImage\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/kgusns.jpg\"><\/div>\n<p><amp-ad width=\"100vw\" height=\"320\" type=\"adsense\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"5405056807\" data-auto-format=\"rspv\" data-full-width=\"\"><\/p>\n<div overflow=\"\"><\/div>\n<p><\/amp-ad><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<blockquote><p>\u201cSeguimos avanzando, abriendo nuevas puertas y haciendo cosas nuevas porque nuestra curiosidad nos impulsa por nuevos caminos. Podemos hacer realidad todos nuestros sue\u00f1os si tenemos el coraje de perseguirlos\u201d. walt disney<\/p><\/blockquote>\n<\/div>\n<div class=\"nImage\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/asfdyf.jpg\"><\/div>\n<div class=\"line nText\">\u00abEspero que nunca nos perdamos nada, todo comenz\u00f3 con un rat\u00f3n\u00bb.<\/div>\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1787826683754973\" data-ad-slot=\"3264820100\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<div class=\"line nHR\">\n<hr>\n<\/div>\n<div class=\"line nText\">\n<h2>Walt Disney recibi\u00f3 muchos premios, como 5 Oscar y 31 Premios de la Academia en sus 65 a\u00f1os de vida.<\/h2>\n<\/div>\n<div class=\"nImage coverImage\"><img decoding=\"async\" src=\"https:\/\/ceotudent.com\/wp-content\/images\/post\/user-5\/da7iai.jpg\"><\/div>\n<div class=\"line nText\"> A los 62 a\u00f1os, en el apogeo de su carrera, una de las figuras m\u00e1s reconocibles del mundo, le diagnosticaron c\u00e1ncer. Estaba tan apasionado por el mundo que cre\u00f3 que le cont\u00f3 emocionado a su hermano Roy sobre sus nuevos proyectos poco antes de fallecer a la edad de 65 a\u00f1os.<\/div>\n<div id=\"empty-line\" class=\"nText \">\n<blockquote><p>\u00abLa risa es atemporal, la imaginaci\u00f3n no tiene edad, los sue\u00f1os son infinitos\u00bb. -Walt Disney<\/p><\/blockquote>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pionero de las pel\u00edculas de dibujos animados, el creador de Disneylandia, Walt Disney, conocido como una de las mentes m\u00e1s creativas del siglo XX; Hasta ese momento, fue objeto de innumerables cr\u00edticas como muchas personas exitosas. Tanto es as\u00ed que fue expulsado del peri\u00f3dico para el que una vez trabaj\u00f3, diciendo que le faltaba&#8230;<\/p>\n","protected":false},"author":9,"featured_media":213899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18019,18017],"tags":[],"class_list":["post-306301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emprendimiento","category-motivacion"],"_links":{"self":[{"href":"https:\/\/ceotudent.com\/es\/wp-json\/wp\/v2\/posts\/306301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceotudent.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceotudent.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceotudent.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/ceotudent.com\/es\/wp-json\/wp\/v2\/comments?post=306301"}],"version-history":[{"count":0,"href":"https:\/\/ceotudent.com\/es\/wp-json\/wp\/v2\/posts\/306301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceotudent.com\/es\/wp-json\/wp\/v2\/media\/213899"}],"wp:attachment":[{"href":"https:\/\/ceotudent.com\/es\/wp-json\/wp\/v2\/media?parent=306301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceotudent.com\/es\/wp-json\/wp\/v2\/categories?post=306301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceotudent.com\/es\/wp-json\/wp\/v2\/tags?post=306301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}